{"id":50,"count":2,"description":"","link":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/tag\/qwocmap\/","name":"#qwocmap","slug":"qwocmap","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#qwocmap Archives - shades magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/tag\/qwocmap\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#qwocmap Archives - shades magazine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/tag\/qwocmap\/\" \/>\n<meta property=\"og:site_name\" content=\"shades magazine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/tag\\\/qwocmap\\\/\",\"url\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/tag\\\/qwocmap\\\/\",\"name\":\"#qwocmap Archives - shades magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/tag\\\/qwocmap\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/tag\\\/qwocmap\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#qwocmap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/#website\",\"url\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/\",\"name\":\"shades magazine\",\"description\":\"Celebrating All Women of Color\",\"publisher\":{\"@id\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/#organization\",\"name\":\"shades magazine\",\"url\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-Screen-Shot-2023-02-24-at-10.07.35-AM.png?fit=577%2C197&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-Screen-Shot-2023-02-24-at-10.07.35-AM.png?fit=577%2C197&ssl=1\",\"width\":577,\"height\":197,\"caption\":\"shades magazine\"},\"image\":{\"@id\":\"https:\\\/\\\/maginecreativeservices.com\\\/shadesmagazine2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#qwocmap Archives - shades magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/tag\/qwocmap\/","og_locale":"en_US","og_type":"article","og_title":"#qwocmap Archives - shades magazine","og_url":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/tag\/qwocmap\/","og_site_name":"shades magazine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/tag\/qwocmap\/","url":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/tag\/qwocmap\/","name":"#qwocmap Archives - shades magazine","isPartOf":{"@id":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/#website"},"breadcrumb":{"@id":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/tag\/qwocmap\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/tag\/qwocmap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/"},{"@type":"ListItem","position":2,"name":"#qwocmap"}]},{"@type":"WebSite","@id":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/#website","url":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/","name":"shades magazine","description":"Celebrating All Women of Color","publisher":{"@id":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/#organization","name":"shades magazine","url":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/maginecreativeservices.com\/shadesmagazine2023\/wp-content\/uploads\/2023\/03\/cropped-Screen-Shot-2023-02-24-at-10.07.35-AM.png?fit=577%2C197&ssl=1","contentUrl":"https:\/\/i0.wp.com\/maginecreativeservices.com\/shadesmagazine2023\/wp-content\/uploads\/2023\/03\/cropped-Screen-Shot-2023-02-24-at-10.07.35-AM.png?fit=577%2C197&ssl=1","width":577,"height":197,"caption":"shades magazine"},"image":{"@id":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/wp-json\/wp\/v2\/tags\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/maginecreativeservices.com\/shadesmagazine2023\/wp-json\/wp\/v2\/posts?tags=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}